{"id":497,"date":"2013-02-08T01:49:22","date_gmt":"2013-02-08T00:49:22","guid":{"rendered":"http:\/\/studinano.com\/WordPress\/?p=497"},"modified":"2024-08-23T17:07:09","modified_gmt":"2024-08-23T16:07:09","slug":"la-liberte-guidant-le-peuple-taguee","status":"publish","type":"post","link":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/","title":{"rendered":"La Libert\u00e9 guidant le peuple tagu\u00e9e"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture&nbsp;: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" data-attachment-id=\"8675\" data-permalink=\"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/la_liberte_guidant_le_peuple_-_eugene_delacroix_-_musee_du_louvre_peintures_rf_129_-_apres_restauration_2024\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/La_Liberte_guidant_le_peuple_-_Eugene_Delacroix_-_Musee_du_Louvre_Peintures_RF_129_-_apres_restauration_2024.jpg?fit=1200%2C960&amp;ssl=1\" data-orig-size=\"1200,960\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\"}' data-image-title=\"La_Libert&eacute;_guidant_le_peuple_-_Eug&egrave;ne_Delacroix_-_Mus&eacute;e_du_Louvre_Peintures_RF_129_-_apr&egrave;s_restauration_2024\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/La_Liberte_guidant_le_peuple_-_Eugene_Delacroix_-_Musee_du_Louvre_Peintures_RF_129_-_apres_restauration_2024.jpg?fit=1024%2C819&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/La_Liberte_guidant_le_peuple_-_Eugene_Delacroix_-_Musee_du_Louvre_Peintures_RF_129_-_apres_restauration_2024.jpg?resize=1024%2C819&#038;ssl=1\" alt=\"Delacroix, Eug&egrave;ne (1798-1863), La liberte guidant le peuple, 1830\n(Allegorie de la revolution de Juillet 1830 , avec un autoportrait). \nHuile sur toile, \nH. 3,60 , L. 2,25. \nParis, Musee du Louvre \/ Lens, Louvre-Lens\" class=\"wp-image-8675\" srcset=\"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/La_Liberte_guidant_le_peuple_-_Eugene_Delacroix_-_Musee_du_Louvre_Peintures_RF_129_-_apres_restauration_2024.jpg?resize=1024%2C819&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/La_Liberte_guidant_le_peuple_-_Eugene_Delacroix_-_Musee_du_Louvre_Peintures_RF_129_-_apres_restauration_2024.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/La_Liberte_guidant_le_peuple_-_Eugene_Delacroix_-_Musee_du_Louvre_Peintures_RF_129_-_apres_restauration_2024.jpg?resize=768%2C614&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/La_Liberte_guidant_le_peuple_-_Eugene_Delacroix_-_Musee_du_Louvre_Peintures_RF_129_-_apres_restauration_2024.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"\/><figcaption class=\"wp-element-caption\">Delacroix, Eug&egrave;ne (1798-1863), La liberte guidant le peuple, 1830<br>(Allegorie de la revolution de Juillet 1830 , avec un autoportrait). <br>Huile sur toile, <br>H. 3,60 , L. 2,25. <br>Paris, Musee du Louvre \/ Lens, Louvre-Lens<\/figcaption><\/figure><hr class=\"wp-block-separator has-alpha-channel-opacity\"><p><span style=\"color: #993300;\"><strong>Je tiens &agrave; vous pr&eacute;venir, cet article est un coup de gueule et pas un article expliquant en d&eacute;tail ce qu&rsquo;est et ce que raconte cette peinture d&rsquo;Eug&egrave;ne Delacroix.<\/strong><\/span><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"><p>La Libert&eacute; guidant le peuple n&rsquo;est pas, &agrave; mes yeux, n&rsquo;importe quel tableau. Ceci est un des tableaux les plus embl&eacute;matiques de ce qu&rsquo;a pu &ecirc;tre la France et de ce qu&rsquo;elle devrait toujours chercher &agrave; &ecirc;tre : <span style=\"color: #000080;\"><strong>une nation qui n&rsquo;h&eacute;sita pas &agrave; faire valoir ses droits et &agrave; les d&eacute;clarer haut et fort<\/strong><\/span>. La France devint la nation des Droits de l&rsquo;Homme gr&acirc;ce &agrave; ses r&eacute;volutionnaires. &Ccedil;a n&rsquo;est pas rien.<\/p>\n\n\n\n<p>Delacroix d&eacute;peint ici ni plus ni moins que <span style=\"color: #000080;\"><strong>la Libert&eacute; elle-m&ecirc;me<\/strong><\/span>, <span style=\"color: #000080;\"><strong>personnifi&eacute;e<\/strong> <\/span>en cette femme portant le bonnet phrygien (symbole des r&eacute;volutionnaires), guidant le peuple. J&rsquo;insiste : la Libert&eacute;, donc, <strong>au m&ecirc;me niveau<\/strong> que le peuple et <strong>le guidant<\/strong>. Vous voyez o&ugrave; je veux en venir ? Nos valeurs (&laquo;&nbsp;Libert&eacute;, &eacute;galit&eacute;, fraternit&eacute;&nbsp;&raquo;) sont mises en image dans ce tableau. Il est un symbole &agrave; lui seul de ce que notre pays dit &ecirc;tre (m&ecirc;me si, malheureusement, il ne l&rsquo;est pas toujours&hellip;) : <strong><span style=\"color: #000080;\">un pays o&ugrave; chacun na&icirc;t libre et &eacute;gaux en droit<\/span><\/strong>.<\/p>\n\n\n\n<p>Ceci est loin d&rsquo;&ecirc;tre un tableau d&eacute;pourvu de sens. C&rsquo;est un tableau <span style=\"color: #000080;\"><strong>primordial<\/strong> <\/span>que chacun devrait respecter au plus haut point et que bon nombre de gens, aujourd&rsquo;hui, ne connaissent pas ou ignorent b&ecirc;tement. Un tableau qui d&eacute;peint une p&eacute;riode de notre histoire que peuvent bien critiquer les bons penseurs d&rsquo;aujourd&rsquo;hui et tous ces gens qui voudraient refaire le proc&egrave;s de nos t&ecirc;tes couronn&eacute;es, voire les remettre au pouvoir (j&rsquo;aimerais tant vous voir transport&eacute;s &agrave; l&rsquo;&eacute;poque ! Comme je rirais de bon c&oelig;ur !) : il est la preuve qu&rsquo;un jour le peuple a su dire &laquo;&nbsp;Non&nbsp;&raquo; de fa&ccedil;on ferme et franche &agrave; un <span style=\"color: #000080;\"><strong>pouvoir totalitariste<\/strong><\/span> afin que nos petites t&ecirc;tes blondes puissent aujourd&rsquo;hui toutes se la p&eacute;ter avec un iPhone &agrave; la main en cour de r&eacute;cr&eacute;ation.<\/p>\n\n\n\n<p>La R&eacute;volution ne se r&eacute;sume pas seulement &agrave; la guillotine et &agrave; la Terreur, comme beaucoup le croient ou essaient de le faire croire. <span style=\"color: #000080;\"><strong>La R&eacute;volution a surtout<\/strong> <strong>mis fin &agrave; un syst&egrave;me injuste<\/strong><\/span>, au sein duquel seule une tr&egrave;s petite part de la population (la Noblesse) s&rsquo;octroyait tous les pouvoirs, toute la libert&eacute; au profit des autres (le Peuple).<br>On peut douter, aujourd&rsquo;hui, au vu des disparit&eacute;s g&eacute;n&eacute;r&eacute;es par notre syst&egrave;me &eacute;conomique (des riches de plus en plus riches, des pauvres de plus en plus pauvres et, surtout, de plus en plus nombreux &agrave; &ecirc;tre pauvres), que les choses se soient v&eacute;ritablement arrang&eacute;es avec le temps, mais il n&rsquo;emp&ecirc;che que c&rsquo;&eacute;tait bien l&agrave; l&rsquo;id&eacute;e premi&egrave;re des R&eacute;volutionnaires.<\/p>\n\n\n\n<p><span style=\"color: #000080;\"><strong>La Libert&eacute;, bon sang !<\/strong><\/span> Combien de ces t&ecirc;tes blondes savent encore ce qu&rsquo;elle signifie vraiment ? Eux, pendus &agrave; longueur de journ&eacute;e sur les r&eacute;seaux sociaux ou le nez coll&eacute; &agrave; l&rsquo;&eacute;cran de leur t&eacute;l&eacute;viseur &agrave; regarder des conneries sur TF1&hellip; Et leurs parents avec eux ! En seriez-vous l&agrave;, si la R&eacute;volution n&rsquo;avait jamais eu lieu ? Auriez-vous vos cong&eacute;s pay&eacute;s pour partir &agrave; la montagne chaque hiver et &agrave; la plage chaque &eacute;t&eacute;, permettant ainsi &agrave; tous les JT de titrer sur les pauvres naufrag&eacute;s de la route pendant que d&rsquo;autres meurent de faim et de froid dans la rue ? Pourriez-vous seulement critiquer librement cet &eacute;tat de fait si nous vivions toujours dans un &eacute;tat totalitaire ? Je rage quand je lis des tweets ou des statuts Facebook stupides, jurant que notre gouvernement actuel est une dictature&hellip; Imb&eacute;ciles ! Le gouvernement est bien des choses mais une dictature&hellip; Ne serait-ce que par <span style=\"color: #000080;\"><strong>respect<\/strong> <\/span>pour les gens qui vivent encore bel et bien, de nos jours, sous le joug de dictateurs ou de r&eacute;gimes totalitaires, <strong><span style=\"color: #000080;\">TAISEZ-VOUS DONC<\/span><\/strong>. <span style=\"color: #808080;\">(Sachant que s&rsquo;il vous arrivait effectivement de dire &ccedil;a &agrave; une personnes parlant effectivement du gouvernement de Fran&ccedil;ais Hollande en ces termes, on vous r&eacute;torquerait &laquo;&nbsp;Vous voyez ! Vous &ecirc;tes les supp&ocirc;ts de la dictature en place !&nbsp;&raquo; Parce que ces gens ne r&eacute;fl&eacute;chissent pas plus loin que le bout de leur nez et sont d&rsquo;une extr&ecirc;me mauvaise fois.)<\/span><\/p>\n\n\n\n<p>Bref.<br>L&rsquo;&eacute;ducation va mal. Elle va mal dans les &eacute;coles et elle va mal dans les familles.<br>Et parmi ces familles, voil&agrave; m&ecirc;me que certaines n&rsquo;h&eacute;sitent plus &agrave; nous pondre des discours d&eacute;gueulasses &agrave; propos du &laquo;&nbsp;mariage pour tous&nbsp;&raquo; et &agrave; mettre leurs enfants en premi&egrave;re ligne, dans des situations qu&rsquo;ils ne sont absolument pas en &acirc;ge de comprendre par eux-m&ecirc;mes. Tout &ccedil;a contre un droit ! <span style=\"color: #000080;\"><strong>Une foutue <em>Libert&eacute;<\/em> !<\/strong> <\/span><\/p>\n\n\n\n<p>Comment peut-on encore supporter <span style=\"color: #000080;\"><strong>l&rsquo;inculture grandissante<\/strong><\/span> dans laquelle nous baignons de plus en plus ? Et, plus encore, cette <span style=\"color: #000080;\"><strong>d&eacute;sinvolture<\/strong> <\/span>avec laquelle certains traitent le sujet : &laquo;&nbsp;Oh.. C&rsquo;est comme &ccedil;a. C&rsquo;est l&rsquo;&eacute;poque qui veut &ccedil;a.&nbsp;&raquo; Mais oui, restons l&agrave;, les bras crois&eacute;s, &agrave; compter le moindre de <em>nos<\/em> centimes, les <em>n&ocirc;tres<\/em>, <em>notre<\/em> propri&eacute;t&eacute;, <em>nous<\/em>, <span style=\"color: #000080;\"><strong>individualistes<\/strong><\/span>, pas les autres, eux peuvent bien crever. Non, voyez-vous, le monde ne se construit pas ainsi. Ca n&rsquo;a jamais &eacute;t&eacute; le cas. M&ecirc;me les hommes pr&eacute;historiques l&rsquo;avaient d&eacute;j&agrave; bien compris : un groupe est fort, l&rsquo;homme seul meurt. Et un homme seul et stupide encore plus vite que les autres.<\/p>\n\n\n\n<p>J&rsquo;enrage&hellip;<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, <em>La Libert&eacute; guidant le peuple<\/em> a &eacute;t&eacute; tagu&eacute;e. La Libert&eacute; salie. Malmen&eacute;e. Oubli&eacute;e. Un jour, ce sont des b&ecirc;tises de cet ordre aussi qui finiront par nous la co&ucirc;ter v&eacute;ritablement. Petit &agrave; petit, comme grignot&eacute;e par les ob&egrave;ses insatiables que nous sommes tous devenus ou en passe de devenir. Bravo !&hellip;<\/p>\n\n\n\n<p>Ce geste me met en col&egrave;re. Il me r&eacute;volte. Et je suis d&rsquo;autant plus triste qu&rsquo;il se soit produit dans ma r&eacute;gion.<\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture&nbsp;: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Je tiens &agrave; vous pr&eacute;venir, cet article est un coup de gueule et pas un article expliquant en d&eacute;tail ce qu&rsquo;est et ce que raconte cette peinture d&rsquo;Eug&egrave;ne Delacroix. La Libert&eacute; guidant le peuple n&rsquo;est pas, &agrave; mes yeux, n&rsquo;importe quel tableau. Ceci est un des tableaux les plus embl&eacute;matiques de ce qu&rsquo;a pu &ecirc;tre [&hellip;]<\/p>","protected":false},"author":1,"featured_media":2723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[1389,2581],"tags":[2270,2276,48,2277,172,2268,2278,333,353,428,700,724,2272,732,733,754,863,4505,2273,2275,2274,985,2271,1072,2269,1073,1217,2279,2280],"class_list":["post-497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog_","category-mes-coleres","tag-2270","tag-allegorie","tag-allegorie-auf-die-julirevolution","tag-allegorie-de-la-liberte","tag-bonnet-phrygien","tag-coup-de-gueule","tag-critique","tag-delacroix","tag-die-freiheit-fuehrt-das-volk","tag-eugene-delacroix","tag-la-liberte-guidant-le-peuple","tag-lens","tag-liberte","tag-liberty-guides-the-people","tag-liberty-leading-the-people","tag-louvre","tag-musee","tag-nord","tag-personnification","tag-personnifie","tag-personnifiee","tag-phrygien","tag-prise-de-la-bastille","tag-revolution","tag-revolution-francaise","tag-revolutionnaire","tag-tag","tag-tague","tag-taguee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Libert\u00e9 guidant le peuple tagu\u00e9e - Studinano, le blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Libert\u00e9 guidant le peuple tagu\u00e9e - Studinano, le blog\" \/>\n<meta property=\"og:description\" content=\"Temps de lecture&nbsp;:  4 minutesJe tiens &agrave; vous pr&eacute;venir, cet article est un coup de gueule et pas un article expliquant en d&eacute;tail ce qu&rsquo;est et ce que raconte cette peinture d&rsquo;Eug&egrave;ne Delacroix. La Libert&eacute; guidant le peuple n&rsquo;est pas, &agrave; mes yeux, n&rsquo;importe quel tableau. Ceci est un des tableaux les plus embl&eacute;matiques de ce qu&rsquo;a pu &ecirc;tre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/\" \/>\n<meta property=\"og:site_name\" content=\"Studinano, le blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ByShou\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ByShou\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-08T00:49:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-23T16:07:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Studinano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Studinano\" \/>\n<meta name=\"twitter:site\" content=\"@Studinano\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Studinano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/\"},\"author\":{\"name\":\"Studinano\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#\\\/schema\\\/person\\\/20b891bb2e9fe0468928431b9c4fa0fd\"},\"headline\":\"La Libert\u00e9 guidant le peuple tagu\u00e9e\",\"datePublished\":\"2013-02-08T00:49:22+00:00\",\"dateModified\":\"2024-08-23T16:07:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/\"},\"wordCount\":1009,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.studinano.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1\",\"keywords\":[\"1789\",\"all\u00e9gorie\",\"Allegorie auf die Julirevolution\",\"all\u00e9gorie de la libert\u00e9\",\"bonnet phrygien\",\"coup de gueule\",\"critique\",\"Delacroix\",\"Die Freiheit fuehrt das Volk\",\"Eug\u00e8ne Delacroix\",\"la Liberte guidant le peuple\",\"lens\",\"libert\u00e9\",\"Liberty guides the people\",\"Liberty leading the People\",\"louvre\",\"mus\u00e9e\",\"nord\",\"personnification\",\"personnifi\u00e9\",\"personnifi\u00e9e\",\"phrygien\",\"prise de la Bastille\",\"R\u00e9volution\",\"R\u00e9volution Fran\u00e7aise\",\"r\u00e9volutionnaire\",\"tag\",\"tagu\u00e9\",\"tagu\u00e9e\"],\"articleSection\":[\"Blog\",\"Mes col\u00e8res\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/\",\"url\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/\",\"name\":\"La Libert\u00e9 guidant le peuple tagu\u00e9e - Studinano, le blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.studinano.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1\",\"datePublished\":\"2013-02-08T00:49:22+00:00\",\"dateModified\":\"2024-08-23T16:07:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.studinano.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.studinano.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1\",\"width\":1000,\"height\":515},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/la-liberte-guidant-le-peuple-taguee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Libert\u00e9 guidant le peuple tagu\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/\",\"name\":\"Studinano, le blog\",\"description\":\"Dans les rouages de l&#039;art et de la culture\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#organization\",\"name\":\"Studinano\",\"url\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.studinano.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-studinano-coccinelle-pieuvre-steampunk.png?fit=1024%2C1024&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.studinano.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-studinano-coccinelle-pieuvre-steampunk.png?fit=1024%2C1024&ssl=1\",\"width\":1024,\"height\":1024,\"caption\":\"Studinano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ByShou\",\"https:\\\/\\\/x.com\\\/Studinano\",\"https:\\\/\\\/www.instagram.com\\\/studinano.art\",\"https:\\\/\\\/www.tiktok.com\\\/@studidinano\",\"https:\\\/\\\/www.threads.net\\\/@studinano.art\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/#\\\/schema\\\/person\\\/20b891bb2e9fe0468928431b9c4fa0fd\",\"name\":\"Studinano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dbaba31327f2aebb9b14355aef067a31a2b7a3e0f2504a76a01e83cfca559a88?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dbaba31327f2aebb9b14355aef067a31a2b7a3e0f2504a76a01e83cfca559a88?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dbaba31327f2aebb9b14355aef067a31a2b7a3e0f2504a76a01e83cfca559a88?s=96&d=identicon&r=g\",\"caption\":\"Studinano\"},\"description\":\"Cr\u00e9atrice et administratrice de Studinano. Artiste plasticienne. Professeure d'Arts Plastiques. Dipl\u00f4m\u00e9e d'un Master de Recherche en Arts Plastiques. Docteure en Sciences de l'Information et de la Communication (SIC) : \\\"La cr\u00e9ation steampunk comme m\u00e9diation renouvel\u00e9e du patrimoine industriel du Bassin Minier en Hauts-de-France\\\"\",\"sameAs\":[\"http:\\\/\\\/www.studinano.com\",\"https:\\\/\\\/www.facebook.com\\\/ByShou\",\"https:\\\/\\\/x.com\\\/@Studinano\"],\"url\":\"https:\\\/\\\/www.studinano.com\\\/blog\\\/author\\\/studinano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Libert\u00e9 guidant le peuple tagu\u00e9e - Studinano, le blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/","og_locale":"fr_FR","og_type":"article","og_title":"La Libert\u00e9 guidant le peuple tagu\u00e9e - Studinano, le blog","og_description":"Temps de lecture&nbsp;:  4 minutesJe tiens &agrave; vous pr&eacute;venir, cet article est un coup de gueule et pas un article expliquant en d&eacute;tail ce qu&rsquo;est et ce que raconte cette peinture d&rsquo;Eug&egrave;ne Delacroix. La Libert&eacute; guidant le peuple n&rsquo;est pas, &agrave; mes yeux, n&rsquo;importe quel tableau. Ceci est un des tableaux les plus embl&eacute;matiques de ce qu&rsquo;a pu &ecirc;tre [&hellip;]","og_url":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/","og_site_name":"Studinano, le blog","article_publisher":"https:\/\/www.facebook.com\/ByShou","article_author":"https:\/\/www.facebook.com\/ByShou","article_published_time":"2013-02-08T00:49:22+00:00","article_modified_time":"2024-08-23T16:07:09+00:00","og_image":[{"width":1000,"height":515,"url":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1","type":"image\/jpeg"}],"author":"Studinano","twitter_card":"summary_large_image","twitter_creator":"@Studinano","twitter_site":"@Studinano","twitter_misc":{"\u00c9crit par":"Studinano","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#article","isPartOf":{"@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/"},"author":{"name":"Studinano","@id":"https:\/\/www.studinano.com\/blog\/#\/schema\/person\/20b891bb2e9fe0468928431b9c4fa0fd"},"headline":"La Libert\u00e9 guidant le peuple tagu\u00e9e","datePublished":"2013-02-08T00:49:22+00:00","dateModified":"2024-08-23T16:07:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/"},"wordCount":1009,"commentCount":2,"publisher":{"@id":"https:\/\/www.studinano.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1","keywords":["1789","all\u00e9gorie","Allegorie auf die Julirevolution","all\u00e9gorie de la libert\u00e9","bonnet phrygien","coup de gueule","critique","Delacroix","Die Freiheit fuehrt das Volk","Eug\u00e8ne Delacroix","la Liberte guidant le peuple","lens","libert\u00e9","Liberty guides the people","Liberty leading the People","louvre","mus\u00e9e","nord","personnification","personnifi\u00e9","personnifi\u00e9e","phrygien","prise de la Bastille","R\u00e9volution","R\u00e9volution Fran\u00e7aise","r\u00e9volutionnaire","tag","tagu\u00e9","tagu\u00e9e"],"articleSection":["Blog","Mes col\u00e8res"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/","url":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/","name":"La Libert\u00e9 guidant le peuple tagu\u00e9e - Studinano, le blog","isPartOf":{"@id":"https:\/\/www.studinano.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#primaryimage"},"image":{"@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1","datePublished":"2013-02-08T00:49:22+00:00","dateModified":"2024-08-23T16:07:09+00:00","breadcrumb":{"@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#primaryimage","url":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1","width":1000,"height":515},{"@type":"BreadcrumbList","@id":"https:\/\/www.studinano.com\/blog\/la-liberte-guidant-le-peuple-taguee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.studinano.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La Libert\u00e9 guidant le peuple tagu\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.studinano.com\/blog\/#website","url":"https:\/\/www.studinano.com\/blog\/","name":"Studinano, le blog","description":"Dans les rouages de l&#039;art et de la culture","publisher":{"@id":"https:\/\/www.studinano.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.studinano.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.studinano.com\/blog\/#organization","name":"Studinano","url":"https:\/\/www.studinano.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.studinano.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2024\/08\/logo-studinano-coccinelle-pieuvre-steampunk.png?fit=1024%2C1024&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2024\/08\/logo-studinano-coccinelle-pieuvre-steampunk.png?fit=1024%2C1024&ssl=1","width":1024,"height":1024,"caption":"Studinano"},"image":{"@id":"https:\/\/www.studinano.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ByShou","https:\/\/x.com\/Studinano","https:\/\/www.instagram.com\/studinano.art","https:\/\/www.tiktok.com\/@studidinano","https:\/\/www.threads.net\/@studinano.art"]},{"@type":"Person","@id":"https:\/\/www.studinano.com\/blog\/#\/schema\/person\/20b891bb2e9fe0468928431b9c4fa0fd","name":"Studinano","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/dbaba31327f2aebb9b14355aef067a31a2b7a3e0f2504a76a01e83cfca559a88?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dbaba31327f2aebb9b14355aef067a31a2b7a3e0f2504a76a01e83cfca559a88?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dbaba31327f2aebb9b14355aef067a31a2b7a3e0f2504a76a01e83cfca559a88?s=96&d=identicon&r=g","caption":"Studinano"},"description":"Cr\u00e9atrice et administratrice de Studinano. Artiste plasticienne. Professeure d'Arts Plastiques. Dipl\u00f4m\u00e9e d'un Master de Recherche en Arts Plastiques. Docteure en Sciences de l'Information et de la Communication (SIC) : \"La cr\u00e9ation steampunk comme m\u00e9diation renouvel\u00e9e du patrimoine industriel du Bassin Minier en Hauts-de-France\"","sameAs":["http:\/\/www.studinano.com","https:\/\/www.facebook.com\/ByShou","https:\/\/x.com\/@Studinano"],"url":"https:\/\/www.studinano.com\/blog\/author\/studinano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/02\/la-libertc3a9-delacroix-vf1-e1420490355498.jpg?fit=1000%2C515&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p4XjvG-81","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":279,"url":"https:\/\/www.studinano.com\/blog\/la-galerie-du-temps\/","url_meta":{"origin":497,"position":0},"title":"Le Louvre Lens et sa galerie du temps","author":"Studinano","date":"8 d\u00e9cembre 2012","format":false,"excerpt":"L\u00e9onard de Vinci, La Vierge, l'Enfant J\u00e9sus et sainte Anne1503 - 1519, Huile sur bois, 168 x 130 cmMus\u00e9e du Louvre, Paris Comme vous le savez peut-\u00eatre, le Louvre vient de s'exporter \u00e0 Lens, tout pr\u00e8s de chez moi. Autant vous dire que je suis joie et bonheur, d'autant plus\u2026","rel":"","context":"Dans &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.studinano.com\/blog\/category\/blog_\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2012\/12\/louvre.jpg?fit=589%2C321&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2012\/12\/louvre.jpg?fit=589%2C321&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2012\/12\/louvre.jpg?fit=589%2C321&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":2881,"url":"https:\/\/www.studinano.com\/blog\/je-suis-charlie\/","url_meta":{"origin":497,"position":1},"title":"JE SUIS CHARLIE !","author":"Studinano","date":"12 janvier 2015","format":"gallery","excerpt":"... Comment commencer un article comme celui-l\u00e0 ?Je me suis longuement pos\u00e9e la question mais je n'ai pas trouv\u00e9 de r\u00e9ponse ad\u00e9quate. D'autant plus que la plupart de mes amis blogueurs ont pr\u00e9f\u00e9r\u00e9 s'abstenir de s'exprimer sur ce qui s'est produit (ce que je comprends et respecte tout \u00e0 fait,\u2026","rel":"","context":"Dans &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.studinano.com\/blog\/category\/blog_\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/01\/je-suis-charlie.png?fit=833%2C413&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/01\/je-suis-charlie.png?fit=833%2C413&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/01\/je-suis-charlie.png?fit=833%2C413&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/01\/je-suis-charlie.png?fit=833%2C413&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6003,"url":"https:\/\/www.studinano.com\/blog\/pere-noel-ed-wheeler\/","url_meta":{"origin":497,"position":2},"title":"Le P\u00e8re No\u00ebl voyage \u00e0 travers l&rsquo;Histoire de l&rsquo;Art gr\u00e2ce \u00e0 Ed Wheeler","author":"Studinano","date":"24 d\u00e9cembre 2017","format":false,"excerpt":"Oh, oh, oh ! J'esp\u00e8re que vous avez \u00e9t\u00e9 sages, cette ann\u00e9e ! Car aujourd'hui nous allons parler, une fois encore (car je l'avais d\u00e9j\u00e0 fait ici) du monsieur tout v\u00eatu de rouge cens\u00e9 vous apporter vos cadeaux ce soir... Le P\u00e8re No\u00ebl bien s\u00fbr ! L'an dernier, il avait\u2026","rel":"","context":"Dans &quot;Bouillon de Culture&quot;","block_context":{"text":"Bouillon de Culture","link":"https:\/\/www.studinano.com\/blog\/category\/blog_\/culture\/"},"img":{"alt_text":"Ed Wheeler revisite la plus c\u00e9l\u00e8bre fresque de la Chapelle Sixtine, \"La Cr\u00e9ation d'Adam\" de Michel-Ange.","src":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2017\/12\/Michaelangelo-Michel-Ange-Creation-of-Adam-Pere-Noel-Santa-Claus-Ed-Wheeler-Studinano.jpg?fit=1200%2C593&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2017\/12\/Michaelangelo-Michel-Ange-Creation-of-Adam-Pere-Noel-Santa-Claus-Ed-Wheeler-Studinano.jpg?fit=1200%2C593&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2017\/12\/Michaelangelo-Michel-Ange-Creation-of-Adam-Pere-Noel-Santa-Claus-Ed-Wheeler-Studinano.jpg?fit=1200%2C593&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2017\/12\/Michaelangelo-Michel-Ange-Creation-of-Adam-Pere-Noel-Santa-Claus-Ed-Wheeler-Studinano.jpg?fit=1200%2C593&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2017\/12\/Michaelangelo-Michel-Ange-Creation-of-Adam-Pere-Noel-Santa-Claus-Ed-Wheeler-Studinano.jpg?fit=1200%2C593&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":209,"url":"https:\/\/www.studinano.com\/blog\/lion-de-monzon\/","url_meta":{"origin":497,"position":3},"title":"Le Lion de Monz\u00f3n &#8211; D\u00e9partement des Arts de l&rsquo;Islam au Louvre","author":"Studinano","date":"22 septembre 2012","format":false,"excerpt":"La situation autour des diverses manifestations islamistes de ces derniers temps me rend bien triste. C'est pourquoi, aujourd'hui, je choisis de plut\u00f4t vous parler de ce qui fait la grandeur de cette culture \u00e0 travers l'ouverture, ces jours-ci, du nouveau d\u00e9partement des Arts de l'Islam au Louvre. Nous allons nous\u2026","rel":"","context":"Dans &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.studinano.com\/blog\/category\/blog_\/"},"img":{"alt_text":"Lion de Monz\u00f3n","src":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2012\/09\/lion_de_monzon-titre.jpg?fit=703%2C372&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2012\/09\/lion_de_monzon-titre.jpg?fit=703%2C372&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2012\/09\/lion_de_monzon-titre.jpg?fit=703%2C372&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2012\/09\/lion_de_monzon-titre.jpg?fit=703%2C372&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3665,"url":"https:\/\/www.studinano.com\/blog\/lelephant-de-la-bastille\/","url_meta":{"origin":497,"position":4},"title":"L&rsquo;\u00e9l\u00e9phant de la Bastille","author":"Studinano","date":"18 mars 2015","format":false,"excerpt":"Aquarelle de Jean-Antoine Alavoine (1776-1834) Dernier projet pour la fontaine de l'\u00c9l\u00e9phant de la Bastille (1809-1810) H : 41 cm, L : 51,8 cm L'aquarelle est contresign\u00e9e par Vivant Denon et Alavoine (architecte du projet) Mus\u00e9e du Louvre, Paris Cet \u00e9l\u00e9phant, pour le moins monumental, aurait pu \u00eatre construit au\u2026","rel":"","context":"Dans &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.studinano.com\/blog\/category\/blog_\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/03\/elephant-de-la-bastille.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/03\/elephant-de-la-bastille.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/03\/elephant-de-la-bastille.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/03\/elephant-de-la-bastille.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2015\/03\/elephant-de-la-bastille.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":844,"url":"https:\/\/www.studinano.com\/blog\/visite-de-latelier-dun-peintre-abel-de-pujol\/","url_meta":{"origin":497,"position":5},"title":"Visite de l&rsquo;atelier d&rsquo;un peintre : Abel de Pujol","author":"Studinano","date":"2 septembre 2013","format":false,"excerpt":"Me voil\u00e0 de retour de vacances ! Des vacances presque studieuses, si je puis dire, car elles ont \u00e9t\u00e9 l'occasion de visiter un petit nombre d'expositions toutes plus remarquables les unes que les autres (j'en profite d'ailleurs pour dire merci aux trois mecs, p\u00e8re, fr\u00e8re et fils\/ch\u00e9ri, qui m'accompagnaient et\u2026","rel":"","context":"Dans &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.studinano.com\/blog\/category\/blog_\/"},"img":{"alt_text":"Adrienne Grandpierre, L'atelier d'Abel de Pujol","src":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/09\/grandpierre-valenciennes-img_0641-23-copie.jpg?fit=1200%2C876&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/09\/grandpierre-valenciennes-img_0641-23-copie.jpg?fit=1200%2C876&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/09\/grandpierre-valenciennes-img_0641-23-copie.jpg?fit=1200%2C876&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/09\/grandpierre-valenciennes-img_0641-23-copie.jpg?fit=1200%2C876&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.studinano.com\/blog\/wp-content\/uploads\/2013\/09\/grandpierre-valenciennes-img_0641-23-copie.jpg?fit=1200%2C876&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/posts\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":0,"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/media\/2723"}],"wp:attachment":[{"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studinano.com\/blog\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}